{"id":30900,"date":"2022-03-11T10:53:14","date_gmt":"2022-03-11T10:53:14","guid":{"rendered":"https:\/\/gastplatsgranna.se\/g16\/"},"modified":"2025-05-28T13:26:54","modified_gmt":"2025-05-28T13:26:54","slug":"g16","status":"publish","type":"page","link":"https:\/\/gastplatsgranna.se\/en\/g16\/","title":{"rendered":"G16"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;36px&#8221; background_color=&#8221;#04566E&#8221; background_color_gradient_start=&#8221;#d8dfe9&#8243; background_color_gradient_end=&#8221;rgba(255,255,255,0)&#8221; max_width=&#8221;35%&#8221; max_width_tablet=&#8221;85%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|desktop&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;10px||||false|false&#8221; box_shadow_style=&#8221;preset4&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1 style=\"text-align: center;\">Location G16<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][wpbs_divi_single_calendar id=&#8221;29&#8243; form_id=&#8221;1&#8243; title=&#8221;no&#8221; display=&#8221;2&#8243; highlighttoday=&#8221;yes&#8221; minimum_days=&#8221;1&#8243; show_date_selection=&#8221;yes&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/wpbs_divi_single_calendar][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div><div id=\"image-map-pro-769\"><\/div><\/div>[\/et_pb_code][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;16px&#8221; custom_margin=&#8221;10px|10px|10px|10px|true|true&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2 style=\"text-align: center;\">Welcome to G\u00e4stplats Gr\u00e4nna!<\/h2>\n<p style=\"text-align: left;\">We at G\u00e4stplats Gr\u00e4nna are happy that you are curious about our brand new facility, which offers a little more than a &#8220;regular&#8221; motorhome site such as a service house with state-of-the-art toilets, showers, dishwashing facilities and a washing machine.<\/p>\n<p style=\"text-align: left;\">When it comes to handling black water, gray water, emptying toilet cassettes and refilling fresh water, we have the very latest equipment from www.camperclean.se, such as the fully automatic machine for toilet cassettes, and all this is included in the daily price, so no extra costs!<\/p>\n<p style=\"text-align: left;\">The site has access to 16A power supply and Wi-Fi.<\/p>\n<p style=\"text-align: left;\"><strong>Price \/ Day<\/strong><br \/> <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Location G16<div class=\"et_pb_module wpbs_divi_single_calendar wpbs_divi_single_calendar_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"wpbs-main-wrapper wpbs-main-wrapper-calendar-29 wpbs-main-wrapper-form-1\"><a class=\"wpbs-visually-hidden wpbs-skip-to-content-link\" title=\"Skip Booking Form\" href=\"#wpbs-booking-form-end\">Skip Booking Form<\/a><div class=\"wpbs-container wpbs-enable-hover wpbs-calendar-29 \" data-id=\"29\" data-show_title=\"0\" data-months_to_show=\"2\" data-start_weekday=\"1\" data-show_legend=\"1\" data-legend_position=\"side\" data-show_button_navigation=\"1\" data-show_selector_navigation=\"1\" data-show_week_numbers=\"0\" data-current_year=\"2026\" data-current_month=\"5\" data-jump_months=\"0\" data-highlight_today=\"1\" data-history=\"1\" data-show_tooltip=\"1\" data-show_prices=\"0\" data-language=\"en\" data-min_width=\"200\" data-max_width=\"380\" data-start_date=\"0\" data-end_date=\"0\" data-changeover_start=\"130\" data-changeover_end=\"131\" data-currency=\"SEK\" data-form_position=\"bottom\" data-current_date=\"1778630400000\" data-show_first_available_date=\"0\" ><div class=\"wpbs-calendars-wrapper wpbs-legend-position-side\"><div class=\"wpbs-legend\"><div class=\"wpbs-legend-item\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-381\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><span class=wpbs-legend-item-name>Selected dates<\/span><\/div><div class=\"wpbs-legend-item\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><span class=wpbs-legend-item-name>Available<\/span><\/div><div class=\"wpbs-legend-item\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-129\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><span class=wpbs-legend-item-name>Booked<\/span><\/div><div class=\"wpbs-legend-item\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-132\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><span class=wpbs-legend-item-name>Closed<\/span><\/div><\/div><div class=\"wpbs-calendars\"><div class=\"wpbs-calendar wpbs-calendar-month-5 wpbs-calendar-year-2026 \"><div class=\"wpbs-calendar-header wpbs-heading\"><div class=\"wpbs-calendar-header-navigation\"><button class=\"wpbs-prev\" aria-label=\"Navigate to previous month\"><span class=\"wpbs-arrow\"><\/span><\/button><div class=\"wpbs-select-container\"><select name=\"wpbs-month-selector-dropdown\" aria-label=\"Calendar month navigation\"><option value=\"1771113600\" >February 2026<\/option><option value=\"1773532800\" >March 2026<\/option><option value=\"1776211200\" >April 2026<\/option><option value=\"1778803200\"  selected='selected'>May 2026<\/option><option value=\"1781481600\" >June 2026<\/option><option value=\"1784073600\" >July 2026<\/option><option value=\"1786752000\" >August 2026<\/option><option value=\"1789430400\" >September 2026<\/option><option value=\"1792022400\" >October 2026<\/option><option value=\"1794700800\" >November 2026<\/option><option value=\"1797292800\" >December 2026<\/option><option value=\"1799971200\" >January 2027<\/option><option value=\"1802649600\" >February 2027<\/option><option value=\"1805068800\" >March 2027<\/option><option value=\"1807747200\" >April 2027<\/option><option value=\"1810339200\" >May 2027<\/option><\/select><\/div><\/div><\/div><div class=\"wpbs-calendar-wrapper\"><table><thead><tr><th>M<\/th><th>T<\/th><th>W<\/th><th>T<\/th><th>F<\/th><th>S<\/th><th>S<\/th><\/tr><\/thead><tbody><tr><td><div class=\"wpbs-date   wpbs-gap  \"  data-price=\"385\" ><div class=\"wpbs-date-inner\"><\/div><\/div><\/td><td><div class=\"wpbs-date   wpbs-gap  \"  data-price=\"385\" ><div class=\"wpbs-date-inner\"><\/div><\/div><\/td><td><div class=\"wpbs-date   wpbs-gap  \"  data-price=\"385\" ><div class=\"wpbs-date-inner\"><\/div><\/div><\/td><td><div class=\"wpbs-date   wpbs-gap  \"  data-price=\"385\" ><div class=\"wpbs-date-inner\"><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-129    \" data-year=\"2026\" data-month=\"5\" data-day=\"1\" data-price=\"385\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-129\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">1<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-129    \" data-year=\"2026\" data-month=\"5\" data-day=\"2\" data-price=\"385\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-129\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">2<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-131    \" data-year=\"2026\" data-month=\"5\" data-day=\"3\" data-price=\"385\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-131\" data-type=\"split\"><div class=\"wpbs-legend-item-icon-color\" ><svg preserveAspectRatio=\"none\" viewBox=\"0 0 200 200\"><polygon points=\"0,0 0,200 200,0\" \/><\/svg><\/div><div class=\"wpbs-legend-item-icon-color\" ><svg preserveAspectRatio=\"none\" viewBox=\"0 0 200 200\"><polygon points=\"0,200 200,200 200,0\" \/><\/svg><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">3<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpbs-date wpbs-legend-item-130    \" data-year=\"2026\" data-month=\"5\" data-day=\"4\" data-price=\"385\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-130\" data-type=\"split\"><div class=\"wpbs-legend-item-icon-color\" ><svg preserveAspectRatio=\"none\" viewBox=\"0 0 200 200\"><polygon points=\"0,0 0,200 200,0\" \/><\/svg><\/div><div class=\"wpbs-legend-item-icon-color\" ><svg preserveAspectRatio=\"none\" viewBox=\"0 0 200 200\"><polygon points=\"0,200 200,200 200,0\" \/><\/svg><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">4<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-129    \" data-year=\"2026\" data-month=\"5\" data-day=\"5\" data-price=\"385\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-129\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">5<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-131    \" data-year=\"2026\" data-month=\"5\" data-day=\"6\" data-price=\"385\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-131\" data-type=\"split\"><div class=\"wpbs-legend-item-icon-color\" ><svg preserveAspectRatio=\"none\" viewBox=\"0 0 200 200\"><polygon points=\"0,0 0,200 200,0\" \/><\/svg><\/div><div class=\"wpbs-legend-item-icon-color\" ><svg preserveAspectRatio=\"none\" viewBox=\"0 0 200 200\"><polygon points=\"0,200 200,200 200,0\" \/><\/svg><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">6<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128    \" data-year=\"2026\" data-month=\"5\" data-day=\"7\" data-price=\"385\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">7<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128    \" data-year=\"2026\" data-month=\"5\" data-day=\"8\" data-price=\"385\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">8<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128    \" data-year=\"2026\" data-month=\"5\" data-day=\"9\" data-price=\"385\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">9<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128    \" data-year=\"2026\" data-month=\"5\" data-day=\"10\" data-price=\"385\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">10<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpbs-date wpbs-legend-item-128    \" data-year=\"2026\" data-month=\"5\" data-day=\"11\" data-price=\"385\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">11<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128    \" data-year=\"2026\" data-month=\"5\" data-day=\"12\" data-price=\"385\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">12<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-130 wpbs-date-today  wpbs-is-bookable \" data-year=\"2026\" data-month=\"5\" data-day=\"13\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-130\" data-type=\"split\"><div class=\"wpbs-legend-item-icon-color\" ><svg preserveAspectRatio=\"none\" viewBox=\"0 0 200 200\"><polygon points=\"0,0 0,200 200,0\" \/><\/svg><\/div><div class=\"wpbs-legend-item-icon-color\" ><svg preserveAspectRatio=\"none\" viewBox=\"0 0 200 200\"><polygon points=\"0,200 200,200 200,0\" \/><\/svg><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">13<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-129    \" data-year=\"2026\" data-month=\"5\" data-day=\"14\" data-price=\"385\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-129\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">14<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-129    \" data-year=\"2026\" data-month=\"5\" data-day=\"15\" data-price=\"385\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-129\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">15<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-129    \" data-year=\"2026\" data-month=\"5\" data-day=\"16\" data-price=\"385\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-129\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">16<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-131   wpbs-is-bookable \" data-year=\"2026\" data-month=\"5\" data-day=\"17\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-131\" data-type=\"split\"><div class=\"wpbs-legend-item-icon-color\" ><svg preserveAspectRatio=\"none\" viewBox=\"0 0 200 200\"><polygon points=\"0,0 0,200 200,0\" \/><\/svg><\/div><div class=\"wpbs-legend-item-icon-color\" ><svg preserveAspectRatio=\"none\" viewBox=\"0 0 200 200\"><polygon points=\"0,200 200,200 200,0\" \/><\/svg><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">17<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"5\" data-day=\"18\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">18<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"5\" data-day=\"19\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">19<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"5\" data-day=\"20\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">20<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"5\" data-day=\"21\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">21<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"5\" data-day=\"22\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">22<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"5\" data-day=\"23\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">23<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"5\" data-day=\"24\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">24<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"5\" data-day=\"25\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">25<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"5\" data-day=\"26\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">26<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"5\" data-day=\"27\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">27<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"5\" data-day=\"28\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">28<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"5\" data-day=\"29\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">29<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"5\" data-day=\"30\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">30<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"5\" data-day=\"31\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">31<\/span><\/div><\/div><\/td><\/tr><\/tbody><\/table><\/div><\/div><div class=\"wpbs-calendar wpbs-calendar-month-6 wpbs-calendar-year-2026 \"><div class=\"wpbs-calendar-header wpbs-heading\"><div class=\"wpbs-calendar-header-navigation\">June 2026<button class=\"wpbs-next\" aria-label=\"Navigate to next month\"><span class=\"wpbs-arrow\"><\/span><\/button><\/div><\/div><div class=\"wpbs-calendar-wrapper\"><table><thead><tr><th>M<\/th><th>T<\/th><th>W<\/th><th>T<\/th><th>F<\/th><th>S<\/th><th>S<\/th><\/tr><\/thead><tbody><tr><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"1\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">1<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"2\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">2<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"3\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">3<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"4\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">4<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"5\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">5<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"6\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">6<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"7\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">7<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"8\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">8<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"9\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">9<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"10\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">10<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"11\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">11<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"12\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">12<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"13\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">13<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"14\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">14<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"15\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">15<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"16\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">16<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"17\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">17<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-130   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"18\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-130\" data-type=\"split\"><div class=\"wpbs-legend-item-icon-color\" ><svg preserveAspectRatio=\"none\" viewBox=\"0 0 200 200\"><polygon points=\"0,0 0,200 200,0\" \/><\/svg><\/div><div class=\"wpbs-legend-item-icon-color\" ><svg preserveAspectRatio=\"none\" viewBox=\"0 0 200 200\"><polygon points=\"0,200 200,200 200,0\" \/><\/svg><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">18<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-129    \" data-year=\"2026\" data-month=\"6\" data-day=\"19\" data-price=\"385\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-129\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">19<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-129    \" data-year=\"2026\" data-month=\"6\" data-day=\"20\" data-price=\"385\" ><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-129\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">20<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-131   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"21\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-131\" data-type=\"split\"><div class=\"wpbs-legend-item-icon-color\" ><svg preserveAspectRatio=\"none\" viewBox=\"0 0 200 200\"><polygon points=\"0,0 0,200 200,0\" \/><\/svg><\/div><div class=\"wpbs-legend-item-icon-color\" ><svg preserveAspectRatio=\"none\" viewBox=\"0 0 200 200\"><polygon points=\"0,200 200,200 200,0\" \/><\/svg><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">21<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"22\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">22<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"23\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">23<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"24\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">24<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"25\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">25<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"26\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">26<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"27\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">27<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"28\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">28<\/span><\/div><\/div><\/td><\/tr><tr><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"29\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">29<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date wpbs-legend-item-128   wpbs-is-bookable \" data-year=\"2026\" data-month=\"6\" data-day=\"30\" data-price=\"385\" tabindex=\"0\"><div class=\"wpbs-legend-item-icon wpbs-legend-item-icon-128\" data-type=\"single\"><div class=\"wpbs-legend-item-icon-color\" ><\/div><div class=\"wpbs-legend-item-icon-color\" ><\/div><\/div><div class=\"wpbs-date-inner\"><span class=\"wpbs-date-number\">30<\/span><\/div><\/div><\/td><td><div class=\"wpbs-date   wpbs-gap  \"  data-price=\"385\" ><div class=\"wpbs-date-inner\"><\/div><\/div><\/td><td><div class=\"wpbs-date   wpbs-gap  \"  data-price=\"385\" ><div class=\"wpbs-date-inner\"><\/div><\/div><\/td><td><div class=\"wpbs-date   wpbs-gap  \"  data-price=\"385\" ><div class=\"wpbs-date-inner\"><\/div><\/div><\/td><td><div class=\"wpbs-date   wpbs-gap  \"  data-price=\"385\" ><div class=\"wpbs-date-inner\"><\/div><\/div><\/td><td><div class=\"wpbs-date   wpbs-gap  \"  data-price=\"385\" ><div class=\"wpbs-date-inner\"><\/div><\/div><\/td><\/tr><\/tbody><\/table><\/div><\/div><\/div><\/div><style>.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-381 div:first-of-type { background-color: #04566e !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-381 div:nth-of-type(2) { background-color: transparent !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-381 div:first-of-type svg { fill: #04566e !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-381 div:nth-of-type(2) svg { fill: transparent !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-128 div:first-of-type { background-color: #689368 !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-128 div:nth-of-type(2) { background-color: transparent !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-128 div:first-of-type svg { fill: #689368 !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-128 div:nth-of-type(2) svg { fill: transparent !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-128 .wpbs-date-number { color: #ffffff !important; }.wpbs-ical-changeover .wpbs-legend-item-icon:after {background-color: #689368;}.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-129 div:first-of-type { background-color: #ff463d !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-129 div:nth-of-type(2) { background-color: transparent !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-129 div:first-of-type svg { fill: #ff463d !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-129 div:nth-of-type(2) svg { fill: transparent !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-129 .wpbs-date-number { color: #ffffff !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-130 div:first-of-type { background-color: #689368 !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-130 div:nth-of-type(2) { background-color: #ff463d !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-130 div:first-of-type svg { fill: #689368 !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-130 div:nth-of-type(2) svg { fill: #ff463d !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-130 .wpbs-date-number { color: #ffffff !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-131 div:first-of-type { background-color: #ff463d !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-131 div:nth-of-type(2) { background-color: #689368 !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-131 div:first-of-type svg { fill: #ff463d !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-131 div:nth-of-type(2) svg { fill: #689368 !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-131 .wpbs-date-number { color: #ffffff !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-132 div:first-of-type { background-color: #d8dfe9 !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-132 div:nth-of-type(2) { background-color: transparent !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-132 div:first-of-type svg { fill: #d8dfe9 !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-132 div:nth-of-type(2) svg { fill: transparent !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-132 .wpbs-date-number { color: #000000 !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-today div:first-of-type { background-color: rgba( 33,150,243, .9 ) !important; }.wpbs-container.wpbs-calendar-29 .wpbs-legend-item-icon-0 div:first-of-type { background-color: #ffffff !important; }.wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-enable-hover .wpbs-is-bookable:hover:not(.wpbs-selected-first):not(.wpbs-selected-last) .wpbs-legend-item-icon div:first-of-type, .wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-date-hover:not(.wpbs-selected-first):not(.wpbs-selected-last) .wpbs-legend-item-icon div:first-of-type, .wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-date-hover.wpbs-selected-first.wpbs-selected-last .wpbs-legend-item-icon div:first-of-type { background-color: #022831 !important; }.wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-enable-hover .wpbs-is-bookable:hover:not(.wpbs-selected-first):not(.wpbs-selected-last) .wpbs-legend-item-icon[data-type=\"split\"] div svg, .wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-date-hover:not(.wpbs-selected-first):not(.wpbs-selected-last) .wpbs-legend-item-icon[data-type=\"split\"] div svg, .wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-legend-item-icon .wpbs-legend-icon-select svg { fill: #022831 !important; }.wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-date-selected:not(.wpbs-selected-first):not(.wpbs-selected-last) .wpbs-legend-item-icon div:first-of-type, .wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-date-selected.wpbs-selected-first.wpbs-selected-last .wpbs-legend-item-icon div:first-of-type, .wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-enable-hover .wpbs-date-selected:hover:not(.wpbs-selected-first):not(.wpbs-selected-last) .wpbs-legend-item-icon div:first-of-type { background-color: #04566e !important; }.wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-date-selected:not(.wpbs-selected-first):not(.wpbs-selected-last) .wpbs-legend-item-icon[data-type=\"split\"] div svg, .wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-enable-hover .wpbs-date-selected:hover:not(.wpbs-selected-first):not(.wpbs-selected-last) .wpbs-legend-item-icon[data-type=\"split\"] div svg, .wpbs-main-wrapper:not(.wpbs-main-wrapper-form-0) .wpbs-date-selected .wpbs-legend-item-icon .wpbs-legend-icon-select svg { fill: #04566e !important; }.wpbs-date-today:not(.wpbs-date-hover):not(.wpbs-date-selected) .wpbs-legend-item-icon {border: 4px solid #b4d330 !important;}<\/style><div class=\"wpbs-container-loaded\" data-just-loaded=\"1\"><\/div><\/div><form method=\"post\" novalidate=\"novalidate\" action=\"#\" id=\"wpbs-form-1\" class=\"wpbs-form-container wpbs-form-1\" data-id=\"1\" data-minimum_days=\"1\" data-maximum_days=\"0\" data-booking_start_day=\"0\" data-booking_end_day=\"0\" data-selection_type=\"multiple\" data-selection_style=\"split\" data-language=\"en\" data-auto_pending=\"1\" data-show_date_selection=\"1\" data-currency=\"SEK\" ><div class=\"wpbs-form-fields\">\r\n        <div class=\"wpbs-form-selected-dates\">\r\n            <div class=\"wpbs-form-selected-date\">\r\n                <div class=\"wpbs-form-field wpbs-form-field-start-date\">\r\n                    <div class=\"wpbs-form-field-label\"><span>Start Date: <\/span><\/div>\r\n                    <div class=\"wpbs-form-field-input\">-<\/div>\r\n                <\/div>\r\n            <\/div>\r\n            <div class=\"wpbs-form-selected-date\">\r\n                <div class=\"wpbs-form-field wpbs-form-field-end-date\">\r\n                    <div class=\"wpbs-form-field-label\"><span>End Date: <\/span><\/div>\r\n                    <div class=\"wpbs-form-field-input\">-<\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"wpbs-form-field wpbs-form-field-text wpbs-form-field-1-1 wpbs-field-layout-default wpbs-field-required\"><div class=\"wpbs-form-field-label\"><label for=\"wpbs-form-field-input-1-1-8a7e2509\">First name<sup class=\"wpbs-field-required-asterisk\">*<\/sup><\/label><\/div><div class=\"wpbs-form-field-input\"><input\r\n            type=\"text\"\r\n            name=\"wpbs-input-1-1\"\r\n            id=\"wpbs-form-field-input-1-1-8a7e2509\"\r\n            value=\"\"\r\n            placeholder=\"\"\r\n            \r\n            \r\n        ><\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-text wpbs-form-field-1-2 wpbs-field-layout-default wpbs-field-required\"><div class=\"wpbs-form-field-label\"><label for=\"wpbs-form-field-input-1-2-8a7e2509\">Last name<sup class=\"wpbs-field-required-asterisk\">*<\/sup><\/label><\/div><div class=\"wpbs-form-field-input\"><input\r\n            type=\"text\"\r\n            name=\"wpbs-input-1-2\"\r\n            id=\"wpbs-form-field-input-1-2-8a7e2509\"\r\n            value=\"\"\r\n            placeholder=\"\"\r\n            \r\n            \r\n        ><\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-text wpbs-form-field-1-21 wpbs-field-layout-default wpbs-field-required\"><div class=\"wpbs-form-field-label\"><label for=\"wpbs-form-field-input-1-21-8a7e2509\">Registration number - Motorhome<sup class=\"wpbs-field-required-asterisk\">*<\/sup><\/label><\/div><div class=\"wpbs-form-field-input\"><input\r\n            type=\"text\"\r\n            name=\"wpbs-input-1-21\"\r\n            id=\"wpbs-form-field-input-1-21-8a7e2509\"\r\n            value=\"\"\r\n            placeholder=\"\"\r\n            \r\n            \r\n        ><\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-phone wpbs-form-field-1-22 wpbs-field-layout-default wpbs-field-required\"><div class=\"wpbs-form-field-label\"><label for=\"wpbs-form-field-input-1-22-8a7e2509\">Mobiltelefon<sup class=\"wpbs-field-required-asterisk\">*<\/sup><\/label><\/div><div class=\"wpbs-form-field-input\"><input\r\n            type=\"text\"\r\n            name=\"wpbs-input-1-22\"\r\n            id=\"wpbs-form-field-input-1-22-8a7e2509\"\r\n            value=\"\"\r\n            placeholder=\"\"\r\n            data-error=\"Invalid phone number.\"\r\n            \r\n        ><\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-email wpbs-form-field-1-4 wpbs-field-layout-default wpbs-field-required\"><div class=\"wpbs-form-field-label\"><label for=\"wpbs-form-field-input-1-4-8a7e2509\">E-mail<sup class=\"wpbs-field-required-asterisk\">*<\/sup><\/label><\/div><div class=\"wpbs-form-field-input\"><input\r\n            type=\"email\"\r\n            name=\"wpbs-input-1-4\"\r\n            id=\"wpbs-form-field-input-1-4-8a7e2509\"\r\n            value=\"\"\r\n            placeholder=\"\"\r\n            \r\n        ><\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-email wpbs-form-field-1-26 wpbs-field-layout-default wpbs-field-required\"><div class=\"wpbs-form-field-label\"><label for=\"wpbs-form-field-input-1-26-8a7e2509\">Repeat E-mail<sup class=\"wpbs-field-required-asterisk\">*<\/sup><\/label><\/div><div class=\"wpbs-form-field-input\"><input\r\n            type=\"email\"\r\n            name=\"wpbs-input-1-26\"\r\n            id=\"wpbs-form-field-input-1-26-8a7e2509\"\r\n            value=\"\"\r\n            placeholder=\"\"\r\n            \r\n        ><\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-checkbox wpbs-form-field-1-16 wpbs-field-layout-default wpbs-field-required\"><div class=\"wpbs-form-field-label\"><span >Terms of purchase<sup class=\"wpbs-field-required-asterisk\">*<\/sup><\/span><\/div><div class=\"wpbs-form-field-input\"><label for=\"wpbs-form-field-input-1-16-0-8a7e2509\"><input\r\n                    type=\"checkbox\"\r\n                    name=\"wpbs-input-1-16[]\"\r\n                    id=\"wpbs-form-field-input-1-16-0-8a7e2509\"\r\n                    value=\"I accept the terms of purchase\"\r\n                    data-value=\"I accept the terms of purchase\"\r\n                    \r\n                    \r\n                > I accept the terms of purchase<span><\/span><\/label><\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-html wpbs-form-field-1-17 wpbs-field-layout-default\"><div class=\"wpbs-form-field-input\"><a href=\"https:\/\/gastplatsgranna.se\/en\/kopvillkor\/\" target=\"_blank\"><u>Terms of purchase<\/u><\/a>\r\n\r\n<\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-total wpbs-form-field-1-7 wpbs-field-layout-default\"><div class=\"wpbs-form-field-label\"><span >Total<\/span><\/div><div class=\"wpbs-form-field-input\"><div class=\"wpbs-total-price wpbs-total-price-1-7\" data-string-item=\"Item\" data-string-total=\"Total\" data-string-select-dates=\"Please select a date first.\">Please select a date first.<\/div><\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-coupon wpbs-form-field-1-24 wpbs-field-layout-default\"><div class=\"wpbs-form-field-label\"><label for=\"wpbs-form-field-input-1-24-8a7e2509\">Coupon<\/label><\/div><div class=\"wpbs-form-field-input\"><div class=\"wpbs-coupon-code\"><input\r\n            type=\"text\"\r\n            name=\"wpbs-input-1-24\"\r\n            id=\"wpbs-form-field-input-1-24-8a7e2509\"\r\n            value=\"\"\r\n            placeholder=\"\"\r\n            \r\n\r\n        ><button class=\"wpbs-coupon-code-button wpbs-coupon-code-add \" data-label=\"Till\u00e4mpa\">Till\u00e4mpa<\/button><\/div><\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-payment_method wpbs-form-field-1-10 wpbs-field-layout-default wpbs-field-required\"><div class=\"wpbs-form-field-label\"><span ><sup class=\"wpbs-field-required-asterisk\">*<\/sup><\/span><\/div><div class=\"wpbs-form-field-input\"><label class=\"wpbs-payment-method-label wpbs-payment-method-label-woocommerce\"><input type=\"radio\" checked name=\"wpbs-input-1-10\" value=\"woocommerce\" > Pay<span><\/span><\/label><p class=\"wpbs-payment-method-description wpbs-payment-method-description-woocommerce wpbs-payment-method-description-open\">Pay when booking.<\/p><\/div><\/div><div class=\"wpbs-form-field wpbs-form-field-html wpbs-form-field-1-28 wpbs-field-layout-default\"><div class=\"wpbs-form-field-input\">If the payment gets stuck or does not go through, a payment link will be sent to your email where you can complete the payment. \r\nThe booking has been created and the place is reserved.\r\nIf you are unsure, you can always contact us!<\/div><\/div><\/div><input type=\"hidden\" name=\"wpbs-upload-token\" value=\"1866ea71\"><input type=\"hidden\" name=\"wpbs-return-url\" value=\"https:\/\/gastplatsgranna.se\/en\/wp-json\/wp\/v2\/pages\/30900\"><input type=\"hidden\" name=\"wpbs-post-id\" value=\"\"><div class=\"wpbs-form-field wpbs-form-submit-button\"><button type=\"submit\" class=\"\" id=\"wpbs-form-submit-1\">Book space<\/button><\/div><style><\/style><\/form><span class=\"wpbs-visually-hidden\" id=\"wpbs-booking-form-end\"><\/span><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div><div id=\"image-map-pro-769\"><\/div><\/div>Welcome to G\u00e4stplats Gr\u00e4nna! We at G\u00e4stplats Gr\u00e4nna are happy that you are curious about our brand new facility, which offers a little more than a &#8220;regular&#8221; motorhome site such as a service house with state-of-the-art toilets, showers, dishwashing facilities and a washing machine. [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-30900","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 17:34:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/gastplatsgranna.se\/en\/wp-json\/wp\/v2\/pages\/30900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gastplatsgranna.se\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gastplatsgranna.se\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gastplatsgranna.se\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/gastplatsgranna.se\/en\/wp-json\/wp\/v2\/comments?post=30900"}],"version-history":[{"count":3,"href":"https:\/\/gastplatsgranna.se\/en\/wp-json\/wp\/v2\/pages\/30900\/revisions"}],"predecessor-version":[{"id":44585,"href":"https:\/\/gastplatsgranna.se\/en\/wp-json\/wp\/v2\/pages\/30900\/revisions\/44585"}],"wp:attachment":[{"href":"https:\/\/gastplatsgranna.se\/en\/wp-json\/wp\/v2\/media?parent=30900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}